{"id":8523,"date":"2023-12-04T08:54:20","date_gmt":"2023-12-04T07:54:20","guid":{"rendered":"https:\/\/cideon-engineering.com\/?p=8523"},"modified":"2023-12-04T10:28:12","modified_gmt":"2023-12-04T09:28:12","slug":"unvergessliche-firmenweihnachtsfeier-in-dresden","status":"publish","type":"post","link":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/","title":{"rendered":"Unvergessliche Firmenweihnachtsfeier in Dresden"},"content":{"rendered":"\n\t<div id=\"gap-1178006560\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1178006560 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-1294375830\">\n\n\n\t<div id=\"col-1997398402\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-62103067\">\n\n\n\t<div id=\"col-298503926\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_533258882\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto5.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Kuppel innen Frauenkirche\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto5.jpg 768w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto5-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_533258882 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1539335382\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Die Vorfreude auf die Weihnachtszeit ist in unserem Unternehmen jedes Jahr gro\u00df, doch dieses Mal war etwas ganz Besonderes geplant. Unsere Firmenweihnachtsfeier sollte nicht nur festlich und fr\u00f6hlich sein, sondern auch ein unvergessliches Erlebnis werden. Und so machten sich die Mitarbeiter und Mitarbeiterinnen aus allen Standorten auf den Weg nach Dresden.<\/p>\n<p>Am sp\u00e4ten Nachmittag trafen wir uns vor der majest\u00e4tischen <strong><a href=\"https:\/\/www.frauenkirche-dresden.de\/\" target=\"_blank\" rel=\"noopener\">Frauenkirche<\/a><\/strong>. Der Anblick allein war schon atemberaubend. Die Geschichte und die Details, die uns dann noch w\u00e4hrend einer fachkundigen F\u00fchrung pr\u00e4sentiert wurden, machten den Besuch zu etwas ganz Besonderem.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-158264197\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-158264197 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-954544684\">\n\n\n\t<div id=\"col-1584444622\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Wir erfuhren von den Herausforderungen des Wiederaufbaus und der Bedeutung dieses beeindruckenden Bauwerks f\u00fcr die Stadt Dresden und die deutsche Geschichte.<\/p>\n<p>Danach ging es dann weiter zum <strong><a href=\"https:\/\/www.dresden1900.de\/\" target=\"_blank\" rel=\"noopener\">Dresden 1900<\/a><\/strong>, einem charmanten Restaurant direkt an der Frauenkirche. Die Atmosph\u00e4re war warm und einladend, mit dekorativen Elementen, die uns in vergangene Zeiten zur\u00fcck versetzten. Es erwartete uns ein festliches Weihnachtsmen\u00fc, das keine W\u00fcnsche offen lie\u00df. Wir genossen die traditionelle s\u00e4chsische K\u00fcche und lie\u00dfen es uns gut gehen. Die Mitarbeiterinnen und Mitarbeiter hatten die Gelegenheit, sich in entspannter Atmosph\u00e4re auszutauschen und das Jahr Revue passieren zu lassen. Wer wollte, konnte auch Pulsnitzer Pfefferkuchen verzieren.<\/p>\n<p>Die Firmenweihnachtsfeier war zweifellos ein weiterer H\u00f6hepunkt in diesem Jahr, die uns mit unvergesslichen Momenten bereicherte und die Bedeutung von Gemeinschaft unterstrich.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1868655121\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1868655121 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-559375956\">\n\n\n\t<div id=\"col-1747809282\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_567993712\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto6.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Kuppelaufstieg Frauenkirche Dresden\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto6.jpg 768w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto6-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_567993712 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-83401122\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1065662736\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto15-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"Blick \u00fcber die Altstadt von Dresden\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto15-768x576.jpg 768w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto15-300x225.jpg 300w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto15.jpg 1024w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1065662736 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-2016741672\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2016741672 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-1255659688\">\n\n\n\t<div id=\"col-320226184\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1343729605\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto9.jpg\" class=\"attachment-large size-large\" alt=\"Anno 1900 am Neumarkt Dresden\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto9.jpg 1024w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto9-300x225.jpg 300w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto9-768x576.jpg 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1343729605 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-794983511\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_685399475\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto11.jpg\" class=\"attachment-large size-large\" alt=\"Festessen im Anno1900\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto11.jpg 1024w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto11-300x225.jpg 300w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto11-768x576.jpg 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_685399475 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-515322257\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-515322257 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-1964247308\">\n\n\n\t<div id=\"col-1557852192\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_910700553\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto14.jpg\" class=\"attachment-large size-large\" alt=\"Verzieren von Pulsnitzer Pfefferkuchen\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto14.jpg 768w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto14-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_910700553 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1077723124\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1554631618\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg\" class=\"attachment-large size-large\" alt=\"Blick auf die Frauenkirche Dresden\" srcset=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg 768w, https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1554631618 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Am 01. Dezember 2023 waren alle Mitarbeiter und Mitarbeiterinnen zur Weihnachtsfeier eingeladen.<\/p>\n","protected":false},"author":8,"featured_media":8537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering<\/title>\n<meta name=\"description\" content=\"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering\" \/>\n<meta property=\"og:description\" content=\"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/\" \/>\n<meta property=\"og:site_name\" content=\"CE Cideon Engineering\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T07:54:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T09:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Kuhnt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Kuhnt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/\"},\"author\":{\"name\":\"Marco Kuhnt\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/#\\\/schema\\\/person\\\/42d192d59d4a9556d2d25f37a69b56bc\"},\"headline\":\"Unvergessliche Firmenweihnachtsfeier in Dresden\",\"datePublished\":\"2023-12-04T07:54:20+00:00\",\"dateModified\":\"2023-12-04T09:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/\"},\"wordCount\":365,\"image\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cideon-engineering.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Foto10.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/\",\"url\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/\",\"name\":\"Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cideon-engineering.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Foto10.jpg\",\"datePublished\":\"2023-12-04T07:54:20+00:00\",\"dateModified\":\"2023-12-04T09:28:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/#\\\/schema\\\/person\\\/42d192d59d4a9556d2d25f37a69b56bc\"},\"description\":\"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cideon-engineering.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Foto10.jpg\",\"contentUrl\":\"https:\\\/\\\/cideon-engineering.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Foto10.jpg\",\"width\":768,\"height\":1024,\"caption\":\"Blick auf die Frauenkirche Dresden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/unvergessliche-firmenweihnachtsfeier-in-dresden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unvergessliche Firmenweihnachtsfeier in Dresden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/\",\"name\":\"CE Cideon Engineering\",\"description\":\"making mobility happen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cideon-engineering.com\\\/de\\\/#\\\/schema\\\/person\\\/42d192d59d4a9556d2d25f37a69b56bc\",\"name\":\"Marco Kuhnt\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering","description":"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/","og_locale":"de_DE","og_type":"article","og_title":"Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering","og_description":"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.","og_url":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/","og_site_name":"CE Cideon Engineering","article_published_time":"2023-12-04T07:54:20+00:00","article_modified_time":"2023-12-04T09:28:12+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg","type":"image\/jpeg"}],"author":"Marco Kuhnt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marco Kuhnt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#article","isPartOf":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/"},"author":{"name":"Marco Kuhnt","@id":"https:\/\/cideon-engineering.com\/de\/#\/schema\/person\/42d192d59d4a9556d2d25f37a69b56bc"},"headline":"Unvergessliche Firmenweihnachtsfeier in Dresden","datePublished":"2023-12-04T07:54:20+00:00","dateModified":"2023-12-04T09:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/"},"wordCount":365,"image":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#primaryimage"},"thumbnailUrl":"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg","articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/","url":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/","name":"Unvergessliche Firmenweihnachtsfeier in Dresden - CE Cideon Engineering","isPartOf":{"@id":"https:\/\/cideon-engineering.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#primaryimage"},"image":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#primaryimage"},"thumbnailUrl":"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg","datePublished":"2023-12-04T07:54:20+00:00","dateModified":"2023-12-04T09:28:12+00:00","author":{"@id":"https:\/\/cideon-engineering.com\/de\/#\/schema\/person\/42d192d59d4a9556d2d25f37a69b56bc"},"description":"Am 01. Dezember 2023 waren die Mitarbeiter und Mitarbeiterinnen aller Standorte zu einer unvergesslichen Firmenweihnachtsfeier eingeladen.","breadcrumb":{"@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#primaryimage","url":"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg","contentUrl":"https:\/\/cideon-engineering.com\/wp-content\/uploads\/2023\/12\/Foto10.jpg","width":768,"height":1024,"caption":"Blick auf die Frauenkirche Dresden"},{"@type":"BreadcrumbList","@id":"https:\/\/cideon-engineering.com\/de\/unvergessliche-firmenweihnachtsfeier-in-dresden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cideon-engineering.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unvergessliche Firmenweihnachtsfeier in Dresden"}]},{"@type":"WebSite","@id":"https:\/\/cideon-engineering.com\/de\/#website","url":"https:\/\/cideon-engineering.com\/de\/","name":"CE Cideon Engineering","description":"making mobility happen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cideon-engineering.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cideon-engineering.com\/de\/#\/schema\/person\/42d192d59d4a9556d2d25f37a69b56bc","name":"Marco Kuhnt"}]}},"_links":{"self":[{"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/posts\/8523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/comments?post=8523"}],"version-history":[{"count":3,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/posts\/8523\/revisions"}],"predecessor-version":[{"id":8550,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/posts\/8523\/revisions\/8550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/media\/8537"}],"wp:attachment":[{"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/media?parent=8523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/categories?post=8523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cideon-engineering.com\/de\/wp-json\/wp\/v2\/tags?post=8523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}